{"id":263,"date":"2020-03-12T14:11:11","date_gmt":"2020-03-12T14:11:11","guid":{"rendered":"https:\/\/www.afiformations.com\/?page_id=263"},"modified":"2026-01-30T15:58:55","modified_gmt":"2026-01-30T15:58:55","slug":"formation-securite-france","status":"publish","type":"page","link":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/","title":{"rendered":"Formation s\u00e9curit\u00e9 France"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"263\" class=\"elementor elementor-263\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9bfa87e elementor-section-height-min-height elementor-section-items-top elementor-section-boxed elementor-section-height-default\" data-id=\"9bfa87e\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-db91e75\" data-id=\"db91e75\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f9bc931 elementor-widget elementor-widget-heading\" data-id=\"f9bc931\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Formation s\u00e9curit\u00e9 France<\/h1>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2f7d570 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2f7d570\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-0e5a117\" data-id=\"0e5a117\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a263ff1 elementor-widget elementor-widget-heading\" data-id=\"a263ff1\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">En FRANCE nous nous appuyons sur des centres de formations habilit\u00e9s pour la validation de la conduite en s\u00e9curit\u00e9.<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9c0a23e elementor-widget elementor-widget-heading\" data-id=\"9c0a23e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Engins de chantier<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-649bd51 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"649bd51\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-0d89f63\" data-id=\"0d89f63\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2b177d5 class-img-grand elementor-widget elementor-widget-image\" data-id=\"2b177d5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg\" class=\"attachment-large size-large wp-image-290\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dacec13 elementor-widget elementor-widget-text-editor\" data-id=\"dacec13\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Pelles hydrauliques, a\u0300 chenilles ou sur pneumatiques, de masse \u2264 6 tonnes.<\/li><li>Chargeuses, a\u0300 chenilles ou sur pneumatiques de masse \u2264 6 tonnes.<\/li><li>Chargeuse-pelleteuse de masse \u2264 6 tonnes,<\/li><li>Moto-basculeurs de masse \u2264 6 tonnes.<\/li><li>Compacteurs de masse \u2264 6 tonnes.<\/li><li>Tracteurs agricoles de puissance \u2264 100 cv (73.6 kW).<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-185f424\" data-id=\"185f424\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a352d32 class-img-grand elementor-widget elementor-widget-image\" data-id=\"a352d32\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-pelle-1024x684.jpg\" class=\"attachment-large size-large wp-image-293\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-pelle-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-pelle-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-pelle-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-pelle.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d79107e elementor-widget elementor-widget-text-editor\" data-id=\"d79107e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<ul><li>Pelles hydrauliques, a\u0300 chenilles ou sur pneumatiques, de masse &gt; 6 tonnes.<\/li><li>Pelles multifonctions.<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-abc6424 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"abc6424\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-56f8727 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"56f8727\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-418816b\" data-id=\"418816b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f4753b6 class-img elementor-widget elementor-widget-image\" data-id=\"f4753b6\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-foreuse-afiformations-1024x684.jpg\" class=\"attachment-large size-large wp-image-296\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-foreuse-afiformations-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-foreuse-afiformations-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-foreuse-afiformations-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-foreuse-afiformations.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-6e7a2f8 elementor-widget elementor-widget-text-editor\" data-id=\"6e7a2f8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 6\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Machines automotrices de sondage ou de forage.<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-83fd68e\" data-id=\"83fd68e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e091f20 class-img elementor-widget elementor-widget-image\" data-id=\"e091f20\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/04\/rail-route-1024x768.jpg\" class=\"attachment-large size-large wp-image-874\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/04\/rail-route-1024x768.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/04\/rail-route-300x225.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/04\/rail-route-768x576.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/04\/rail-route-1536x1152.jpg 1536w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/04\/rail-route-1568x1176.jpg 1568w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/04\/rail-route.jpg 2000w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5c4737f elementor-widget elementor-widget-text-editor\" data-id=\"5c4737f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 6\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Pelles hydrauliques rail-route a\u0300 de\u0301placement se\u0301quentiel.<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-ecbe7d4\" data-id=\"ecbe7d4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5e73467 class-img elementor-widget elementor-widget-image\" data-id=\"5e73467\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargeuse-afiformations-1024x684.jpg\" class=\"attachment-large size-large wp-image-303\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargeuse-afiformations-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargeuse-afiformations-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargeuse-afiformations-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargeuse-afiformations.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-fe7a5bf elementor-widget elementor-widget-text-editor\" data-id=\"fe7a5bf\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 6\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Chargeuses sur pneumatiques, de masse &gt; 6 t.<\/li><li>Chargeuses-pelleteuses de masse &gt; 6 t,<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-804ba32 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"804ba32\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d0b82b2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d0b82b2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f27be65\" data-id=\"f27be65\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-33a7a77 class-img elementor-widget elementor-widget-image\" data-id=\"33a7a77\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-bouteurs-1024x684.jpg\" class=\"attachment-large size-large wp-image-305\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-bouteurs-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-bouteurs-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-bouteurs-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-bouteurs.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c2ea85d elementor-widget elementor-widget-text-editor\" data-id=\"c2ea85d\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 6\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 6\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Bouteurs.<\/li><li>Chargeuses a\u0300 chenilles de masse &gt; 6 t.<\/li><\/ul><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-466ea34\" data-id=\"466ea34\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f8f3516 class-img elementor-widget elementor-widget-image\" data-id=\"f8f3516\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-niveleuse-1024x684.jpg\" class=\"attachment-large size-large wp-image-307\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-niveleuse-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-niveleuse-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-niveleuse-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-niveleuse.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ac105a8 elementor-widget elementor-widget-text-editor\" data-id=\"ac105a8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 6\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 6\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Niveleuses automotrices.<\/p><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-66f966b\" data-id=\"66f966b\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8d4badb class-img elementor-widget elementor-widget-image\" data-id=\"8d4badb\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-compacteur-1024x684.jpg\" class=\"attachment-large size-large wp-image-309\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-compacteur-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-compacteur-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-compacteur-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-compacteur.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-021e056 elementor-widget elementor-widget-text-editor\" data-id=\"021e056\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 6\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Compacteurs, a\u0300 cylindres, a\u0300 pneumatiques ou mixtes, de masse &gt; 6 t.<\/li><li>Compacteurs a\u0300 pieds dameurs de masse &gt; 6 t.<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-50c3a8d elementor-align-center elementor-widget elementor-widget-button\" data-id=\"50c3a8d\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1a39f3a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1a39f3a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1d16c77\" data-id=\"1d16c77\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-133bffe class-img elementor-widget elementor-widget-image\" data-id=\"133bffe\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-tombereaux-1024x768.jpg\" class=\"attachment-large size-large wp-image-312\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-tombereaux-1024x768.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-tombereaux-300x225.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-tombereaux-768x576.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-tombereaux.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5d35953 elementor-widget elementor-widget-text-editor\" data-id=\"5d35953\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 7\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Tombereaux, rigides ou articule\u0301s.<\/li><li>Moto-basculeurs de masse &gt; 6t.<\/li><li>Tracteurs agricoles de puissance &gt; 100 cv (73.6 kW).<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-1f73f71\" data-id=\"1f73f71\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-42df826 class-img elementor-widget elementor-widget-image\" data-id=\"42df826\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chariot-manutention-1024x768.jpg\" class=\"attachment-large size-large wp-image-314\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chariot-manutention-1024x768.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chariot-manutention-300x225.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chariot-manutention-768x576.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chariot-manutention.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ca59db6 elementor-widget elementor-widget-text-editor\" data-id=\"ca59db6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 7\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Chariots de manutention tout-terrain a\u0300 conducteur porte\u0301 a\u0300 ma\u0302t.<\/li><li>Chariots de manutention tout- terrain a\u0300 conducteur porte\u0301 a\u0300 fle\u0300che te\u0301lescopique.<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9cdcbbe\" data-id=\"9cdcbbe\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0539fe2 class-img elementor-widget elementor-widget-image\" data-id=\"0539fe2\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargement-dechargement-1024x768.jpg\" class=\"attachment-large size-large wp-image-316\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargement-dechargement-1024x768.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargement-dechargement-300x225.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargement-dechargement-768x576.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R482-chargement-dechargement.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5fcf490 elementor-widget elementor-widget-text-editor\" data-id=\"5fcf490\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 7\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>De\u0301placement et chargement \/ de\u0301chargement sur porte-engins des engins de chantier des cate\u0301gories A a\u0300 F, sans activite\u0301 de production, pour de\u0301monstration ou essais.<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-d84af6c elementor-align-center elementor-widget elementor-widget-button\" data-id=\"d84af6c\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-502c2b4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"502c2b4\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-2cd252d\" data-id=\"2cd252d\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b48a487 elementor-widget elementor-widget-heading\" data-id=\"b48a487\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Grues mobiles<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cf547b7 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cf547b7\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-ba34ff6\" data-id=\"ba34ff6\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-36f1192 class-img-grand elementor-widget elementor-widget-image\" data-id=\"36f1192\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-1024x683.jpg\" class=\"attachment-large size-large wp-image-319\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-086400c elementor-widget elementor-widget-text-editor\" data-id=\"086400c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 8\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Grue automotrice a\u0300 fle\u0300che treillis qui peut e\u0302tre monte\u0301e sur un ma\u0302t (tour) capable de se de\u0301placer en charge ou a\u0300 vide sans avoir besoin de voie de roulement fixe et qui demeure stable sous l\u2019influence de la gravite\u0301.<\/p><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-7de109e\" data-id=\"7de109e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3094cb4 class-img-grand elementor-widget elementor-widget-image\" data-id=\"3094cb4\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-grue-1024x683.jpg\" class=\"attachment-large size-large wp-image-321\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-grue-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-grue-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-grue-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R483-grue.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b372c96 elementor-widget elementor-widget-text-editor\" data-id=\"b372c96\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 8\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Grue automotrice a\u0300 fle\u0300che te\u0301lescopique qui peut e\u0302tre monte\u0301e sur un ma\u0302t (tour), capable de se de\u0301placer en charge ou<br \/>a\u0300 vide sans avoir besoin de voie de roulement fixe et qui demeure stable sous l\u2019influence de la gravite\u0301.<\/p><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-cea9028 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"cea9028\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-1971511\" data-id=\"1971511\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-895c10e elementor-widget elementor-widget-text-editor\" data-id=\"895c10e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous sugg\u00e9rons en compl\u00e9ment les formations suivantes :<\/p><ul><li>\u00e9linguer \u2013 techniques d\u2019\u00e9lingage<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-07c0bb7 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"07c0bb7\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-495da84 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"495da84\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-12a973f\" data-id=\"12a973f\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e3f1863 elementor-widget elementor-widget-heading\" data-id=\"e3f1863\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Ponts roulants portiques<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-65b0b94 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"65b0b94\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-846ece7\" data-id=\"846ece7\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-145dfd8 class-img-grand elementor-widget elementor-widget-image\" data-id=\"145dfd8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afiformations-1024x683.jpg\" class=\"attachment-large size-large wp-image-324\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afiformations-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afiformations-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afiformations-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afiformations.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7bd4043 elementor-widget elementor-widget-text-editor\" data-id=\"7bd4043\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Pont roulant et portique a\u0300 commande au sol (filaire ou te\u0301le\u0301commande).<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-e881ad1\" data-id=\"e881ad1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-595b07b class-img-grand elementor-widget elementor-widget-image\" data-id=\"595b07b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afi-1024x683.jpg\" class=\"attachment-large size-large wp-image-326\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afi-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afi-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afi-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R484-pont-roulant-afi.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-70d513e elementor-widget elementor-widget-text-editor\" data-id=\"70d513e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>Pont roulant et portique a\u0300 commande en cabine.<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0bdaba6 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0bdaba6\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-082fc5d\" data-id=\"082fc5d\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d872466 elementor-widget elementor-widget-text-editor\" data-id=\"d872466\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous sugg\u00e9rons en compl\u00e9ment les formations suivantes :<\/p>\n<ul>\n<li>travaux en hauteur &#8211; port du harnais<\/li>\n<li>\u00e9linguer &#8211; technique d&rsquo;\u00e9lingage<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-84da684 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"84da684\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-f47b85b\" data-id=\"f47b85b\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3558c7e elementor-widget elementor-widget-heading\" data-id=\"3558c7e\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chariots gerbeurs \u00e0 conducteur accompagnant<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5d0ac6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5d0ac6c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-2eaae98\" data-id=\"2eaae98\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c011a3f class-img-grand elementor-widget elementor-widget-image\" data-id=\"c011a3f\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-afiformations-1024x683.jpg\" class=\"attachment-large size-large wp-image-329\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-afiformations-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-afiformations-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-afiformations-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-afiformations.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-ce6e011 elementor-widget elementor-widget-text-editor\" data-id=\"ce6e011\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Gerbeurs automoteurs a\u0300 conducteur accompagnant (1,20 m &lt; hauteur de leve\u0301e \u2264 2,50 m).<\/p><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6ee0780\" data-id=\"6ee0780\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-585ad4e class-img-grand elementor-widget elementor-widget-image\" data-id=\"585ad4e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-gerbeur-1024x683.jpg\" class=\"attachment-large size-large wp-image-331\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-gerbeur-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-gerbeur-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-gerbeur-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R485-gerbeur.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f971d6e elementor-widget elementor-widget-text-editor\" data-id=\"f971d6e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Gerbeurs automoteurs a\u0300 conducteur accompagnant (hauteur de leve\u0301e &gt; 2,50 m)<\/p><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-98c9caf elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"98c9caf\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-c2604a5\" data-id=\"c2604a5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b1468fc elementor-widget elementor-widget-text-editor\" data-id=\"b1468fc\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous sugg\u00e9rons en compl\u00e9ment les formations suivantes :<\/p>\n<ul>\n<li>arrimage sur v\u00e9hicule routier<\/li>\n<\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-65985ee elementor-align-center elementor-widget elementor-widget-button\" data-id=\"65985ee\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-3ef615c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3ef615c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-9bd5b07\" data-id=\"9bd5b07\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3dadc45 elementor-widget elementor-widget-heading\" data-id=\"3dadc45\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Nacelles<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1914434 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1914434\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-e704e1c\" data-id=\"e704e1c\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e35daf8 class-img elementor-widget elementor-widget-image\" data-id=\"e35daf8\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-1024x683.jpg\" class=\"attachment-large size-large wp-image-334\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a81088c elementor-widget elementor-widget-text-editor\" data-id=\"a81088c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 11\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>PEMP verticale<\/p><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-39886f1\" data-id=\"39886f1\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e6543ab class-img elementor-widget elementor-widget-image\" data-id=\"e6543ab\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-multidirectionnelle-1024x683.jpg\" class=\"attachment-large size-large wp-image-336\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-multidirectionnelle-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-multidirectionnelle-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-multidirectionnelle-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R486-pemp-multidirectionnelle.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d3211c5 elementor-widget elementor-widget-text-editor\" data-id=\"d3211c5\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 11\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>PEMP multidirectionnelle<\/p><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-966a59f\" data-id=\"966a59f\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f25aecb elementor-widget elementor-widget-text-editor\" data-id=\"f25aecb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 11\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Conduite hors production des PEMP des Cat A ou B<br \/>De\u0301placement, chargement \/ de\u0301chargement sur porte-engins, transfert de toutes les PEMP de Cat A ou B sans activite\u0301 de production, pour la maintenance, pour de\u0301monstrations ou pour essais.<\/p><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4bd3d57 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4bd3d57\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-b01e0e0\" data-id=\"b01e0e0\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-66cdea6 elementor-widget elementor-widget-text-editor\" data-id=\"66cdea6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous sugg\u00e9rons en compl\u00e9ment les formations suivantes :<\/p><ul><li>travaux en hauteur &#8211; port du harnais<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-42bbc0c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"42bbc0c\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-abdb859\" data-id=\"abdb859\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-06896d4 elementor-widget elementor-widget-heading\" data-id=\"06896d4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Grues \u00e0 tour<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1112626 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1112626\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-6a0a70e\" data-id=\"6a0a70e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8dc2272 class-img elementor-widget elementor-widget-image\" data-id=\"8dc2272\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-1024x683.jpg\" class=\"attachment-large size-large wp-image-339\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a1104ce elementor-widget elementor-widget-text-editor\" data-id=\"a1104ce\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 12\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Grue a\u0300 tour a\u0300 montage par e\u0301le\u0301ments, a\u0300 fle\u0300che distributrice (GME).<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-17b16aa\" data-id=\"17b16aa\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c01e90b class-img elementor-widget elementor-widget-image\" data-id=\"c01e90b\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-elevable-afiformations-1024x683.jpg\" class=\"attachment-large size-large wp-image-341\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-elevable-afiformations-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-elevable-afiformations-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-elevable-afiformations-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-grue-elevable-afiformations.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2159167 elementor-widget elementor-widget-text-editor\" data-id=\"2159167\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 12\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Grue a\u0300 tour a\u0300 montage par e\u0301le\u0301ments, a\u0300 fle\u0300che relevable.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-a01c7ed\" data-id=\"a01c7ed\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9506dda class-img elementor-widget elementor-widget-image\" data-id=\"9506dda\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-gma-1024x683.jpg\" class=\"attachment-large size-large wp-image-343\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-gma-1024x683.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-gma-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-gma-768x512.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R487-gma.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88346f6 elementor-widget elementor-widget-text-editor\" data-id=\"88346f6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 12\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Grue a\u0300 tour a\u0300 montage automatise\u0301 (GMA).<\/p><\/div><\/div><div class=\"layoutArea\"><div class=\"column\"><p>\u00a0<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b0435fb elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b0435fb\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-cc49be4\" data-id=\"cc49be4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7ca98e8 elementor-widget elementor-widget-text-editor\" data-id=\"7ca98e8\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous sugg\u00e9rons en compl\u00e9ment les formations suivantes :<\/p><ul><li>\u00e9linguer \u2013 techniques d\u2019\u00e9lingage<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-159fa75 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"159fa75\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6d4fd79 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6d4fd79\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-1846f92\" data-id=\"1846f92\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-e9a77e6 elementor-widget elementor-widget-heading\" data-id=\"e9a77e6\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Chariots \u00e9l\u00e9vateurs<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-57cdc9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"57cdc9a\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-9efc29a\" data-id=\"9efc29a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ebaa08d class-img elementor-widget elementor-widget-image\" data-id=\"ebaa08d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-transpalette-1024x684.jpg\" class=\"attachment-large size-large wp-image-346\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-transpalette-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-transpalette-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-transpalette-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-transpalette.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-91614eb elementor-widget elementor-widget-text-editor\" data-id=\"91614eb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 11\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Pre\u0301parateurs de commande sans e\u0301le\u0301vation du poste de conduite (hauteur de leve\u0301e \u2264 1,20 m).<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-0f6bfac\" data-id=\"0f6bfac\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ccfcf99 class-img elementor-widget elementor-widget-image\" data-id=\"ccfcf99\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"640\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-1B.jpg\" class=\"attachment-large size-large wp-image-605\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-1B.jpg 640w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-1B-300x300.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-1B-150x150.jpg 150w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0e744fe elementor-widget elementor-widget-text-editor\" data-id=\"0e744fe\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div title=\"Page 9\"><ul><li><div title=\"Page 11\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Gerbeurs a\u0300 conducteur porte\u0301 (hauteur de leve\u0301e &gt; 1,20 m).<\/p><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-406dc94\" data-id=\"406dc94\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82b280d class-img elementor-widget elementor-widget-image\" data-id=\"82b280d\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r489-chariot.jpg\" class=\"attachment-large size-large wp-image-349\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r489-chariot.jpg 800w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r489-chariot-300x225.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r489-chariot-768x576.jpg 768w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c1488b6 elementor-widget elementor-widget-text-editor\" data-id=\"c1488b6\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 11\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Chariots a\u0300 plateau porteur (capacite\u0301 de charge \u2264 2 tonnes).<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-9ce2096 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"9ce2096\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-796010b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"796010b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-84c3fa8\" data-id=\"84c3fa8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ce518ea class-img elementor-widget elementor-widget-image\" data-id=\"ce518ea\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-chariot-tracteur-1024x684.jpg\" class=\"attachment-large size-large wp-image-351\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-chariot-tracteur-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-chariot-tracteur-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-chariot-tracteur-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-chariot-tracteur.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-45caf82 elementor-widget elementor-widget-text-editor\" data-id=\"45caf82\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div title=\"Page 9\"><ul><li><div title=\"Page 11\"><div title=\"Page 13\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Chariots tracteurs industriels (capacite\u0301 de traction \u2264 25 tonnes).<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-8380071\" data-id=\"8380071\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-d70aa48 class-img elementor-widget elementor-widget-image\" data-id=\"d70aa48\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afi-1024x684.jpg\" class=\"attachment-large size-large wp-image-353\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afi-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afi-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afi-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afi.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-8435c5a elementor-widget elementor-widget-text-editor\" data-id=\"8435c5a\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div title=\"Page 9\"><ul><li><div title=\"Page 11\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Chariots e\u0301le\u0301vateurs frontaux en porte a\u0300 faux (capacite\u0301 nominale \u2264 6 tonnes).<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-f2bbd38\" data-id=\"f2bbd38\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-0a2a320 class-img elementor-widget elementor-widget-image\" data-id=\"0a2a320\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afiformations-1024x684.jpg\" class=\"attachment-large size-large wp-image-355\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afiformations-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afiformations-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afiformations-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R489-afiformations.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-88d1d68 elementor-widget elementor-widget-text-editor\" data-id=\"88d1d68\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 11\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Chariots e\u0301le\u0301vateurs frontaux en porte a\u0300 faux (capacite\u0301 nominale &gt; 6 tonnes)<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-59f83dc elementor-align-center elementor-widget elementor-widget-button\" data-id=\"59f83dc\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-0816371 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0816371\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7930fb5\" data-id=\"7930fb5\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-82bc00e class-img elementor-widget elementor-widget-image\" data-id=\"82bc00e\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-mat-afi-formations-1024x684.jpg\" class=\"attachment-large size-large wp-image-357\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-mat-afi-formations-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-mat-afi-formations-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-mat-afi-formations-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-mat-afi-formations.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f53839 elementor-widget elementor-widget-text-editor\" data-id=\"7f53839\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div title=\"Page 9\"><ul><li><div title=\"Page 11\"><div title=\"Page 13\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Chariots e\u0301le\u0301vateurs a\u0300 ma\u0302t re\u0301tractable.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-7246f80\" data-id=\"7246f80\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fbab611 class-img elementor-widget elementor-widget-image\" data-id=\"fbab611\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"684\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-caces-R489-1024x684.jpg\" class=\"attachment-large size-large wp-image-359\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-caces-R489-1024x684.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-caces-R489-300x200.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-caces-R489-768x513.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/chariot-elevateur-caces-R489.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85c06c1 elementor-widget elementor-widget-text-editor\" data-id=\"85c06c1\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li>E\u0301le\u0301vateurs a\u0300 poste de conduite e\u0301levable (hauteur de plancher &gt; 1,20 m).<\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-97ba824\" data-id=\"97ba824\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ec3a445 elementor-widget elementor-widget-text-editor\" data-id=\"ec3a445\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div title=\"Page 9\"><ul><li><div title=\"Page 11\"><div title=\"Page 13\"><div title=\"Page 13\"><div class=\"page\" title=\"Page 13\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p>Conduite hors production des chariots de toutes les cate\u0301gories.<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d3d94df elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d3d94df\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-06b2fab\" data-id=\"06b2fab\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-39c423e elementor-widget elementor-widget-text-editor\" data-id=\"39c423e\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous sugg\u00e9rons en compl\u00e9ment les formations suivantes :<\/p><ul><li>arrimage sur v\u00e9hicule routier<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-368f20f elementor-align-center elementor-widget elementor-widget-button\" data-id=\"368f20f\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-588c96d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"588c96d\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8cb34f4\" data-id=\"8cb34f4\" data-element_type=\"column\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4e3dad4 elementor-widget elementor-widget-heading\" data-id=\"4e3dad4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Grues auxiliaires<\/h2>\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-d285302 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d285302\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-66582c4\" data-id=\"66582c4\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-09f2b80 elementor-widget elementor-widget-text-editor\" data-id=\"09f2b80\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"page\" title=\"Page 9\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><ul><li><div class=\"page\" title=\"Page 10\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><div class=\"page\" title=\"Page 12\"><div class=\"section\"><div class=\"layoutArea\"><div class=\"column\"><p class=\"h1--node\">Grue Auxiliaire de Chargement de V\u00e9hicules<\/p><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/li><\/ul><\/div><\/div><\/div><\/div>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9c04d2a\" data-id=\"9c04d2a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5f37bdf elementor-widget elementor-widget-image\" data-id=\"5f37bdf\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"680\" src=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R490-afi-1024x680.jpg\" class=\"attachment-large size-large wp-image-365\" alt=\"\" srcset=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R490-afi-1024x680.jpg 1024w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R490-afi-300x199.jpg 300w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R490-afi-768x510.jpg 768w, https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-R490-afi.jpg 1200w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-233f2a4 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"233f2a4\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-267b579\" data-id=\"267b579\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9c67c27 elementor-widget elementor-widget-text-editor\" data-id=\"9c67c27\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<p>Nous sugg\u00e9rons en compl\u00e9ment les formations suivantes :<\/p><ul><li>arrimage sur v\u00e9hicule routier<\/li><\/ul>\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-6f00ca2 elementor-align-center elementor-widget elementor-widget-button\" data-id=\"6f00ca2\" data-element_type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/www.afiformations.com\/fr\/contact\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Contactez-nous<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>En FRANCE nous nous appuyons sur des centres de formations habilit\u00e9s pour la validation de la conduite en s\u00e9curit\u00e9. Engins de chantier Pelles hydrauliques, a\u0300 chenilles ou sur pneumatiques, de masse \u2264 6 tonnes. Chargeuses, a\u0300 chenilles ou sur pneumatiques de masse \u2264 6 tonnes. Chargeuse-pelleteuse de masse \u2264 6 tonnes, Moto-basculeurs de masse \u2264 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":108,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"elementor_header_footer","meta":{"site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"set","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"class_list":["post-263","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v24.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Formation s\u00e9curit\u00e9 France - AFI Formations<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Formation s\u00e9curit\u00e9 France - AFI Formations\" \/>\n<meta property=\"og:description\" content=\"En FRANCE nous nous appuyons sur des centres de formations habilit\u00e9s pour la validation de la conduite en s\u00e9curit\u00e9. Engins de chantier Pelles hydrauliques, a\u0300 chenilles ou sur pneumatiques, de masse \u2264 6 tonnes. Chargeuses, a\u0300 chenilles ou sur pneumatiques de masse \u2264 6 tonnes. Chargeuse-pelleteuse de masse \u2264 6 tonnes, Moto-basculeurs de masse \u2264 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/\" \/>\n<meta property=\"og:site_name\" content=\"AFI Formations\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-30T15:58:55+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/\",\"url\":\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/\",\"name\":\"Formation s\u00e9curit\u00e9 France - AFI Formations\",\"isPartOf\":{\"@id\":\"https:\/\/www.afiformations.com\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg\",\"datePublished\":\"2020-03-12T14:11:11+00:00\",\"dateModified\":\"2026-01-30T15:58:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#primaryimage\",\"url\":\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg\",\"contentUrl\":\"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.afiformations.com\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"S\u00e9curit\u00e9\",\"item\":\"https:\/\/www.afiformations.com\/fr\/securite\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Formation s\u00e9curit\u00e9 France\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.afiformations.com\/fr\/#website\",\"url\":\"https:\/\/www.afiformations.com\/fr\/\",\"name\":\"AFI Formations\",\"description\":\"Centre de formations Luxembourg\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.afiformations.com\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Formation s\u00e9curit\u00e9 France - AFI Formations","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/","og_locale":"fr_FR","og_type":"article","og_title":"Formation s\u00e9curit\u00e9 France - AFI Formations","og_description":"En FRANCE nous nous appuyons sur des centres de formations habilit\u00e9s pour la validation de la conduite en s\u00e9curit\u00e9. Engins de chantier Pelles hydrauliques, a\u0300 chenilles ou sur pneumatiques, de masse \u2264 6 tonnes. Chargeuses, a\u0300 chenilles ou sur pneumatiques de masse \u2264 6 tonnes. Chargeuse-pelleteuse de masse \u2264 6 tonnes, Moto-basculeurs de masse \u2264 [&hellip;]","og_url":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/","og_site_name":"AFI Formations","article_modified_time":"2026-01-30T15:58:55+00:00","og_image":[{"url":"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/","url":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/","name":"Formation s\u00e9curit\u00e9 France - AFI Formations","isPartOf":{"@id":"https:\/\/www.afiformations.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#primaryimage"},"image":{"@id":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#primaryimage"},"thumbnailUrl":"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg","datePublished":"2020-03-12T14:11:11+00:00","dateModified":"2026-01-30T15:58:55+00:00","breadcrumb":{"@id":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#primaryimage","url":"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg","contentUrl":"https:\/\/www.afiformations.com\/wp-content\/uploads\/2020\/03\/caces-r482-pelle-afi-formation-1024x684.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.afiformations.com\/fr\/securite\/formation-securite-france\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.afiformations.com\/fr\/"},{"@type":"ListItem","position":2,"name":"S\u00e9curit\u00e9","item":"https:\/\/www.afiformations.com\/fr\/securite\/"},{"@type":"ListItem","position":3,"name":"Formation s\u00e9curit\u00e9 France"}]},{"@type":"WebSite","@id":"https:\/\/www.afiformations.com\/fr\/#website","url":"https:\/\/www.afiformations.com\/fr\/","name":"AFI Formations","description":"Centre de formations Luxembourg","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.afiformations.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"}]}},"_links":{"self":[{"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/pages\/263"}],"collection":[{"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/comments?post=263"}],"version-history":[{"count":59,"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/pages\/263\/revisions"}],"predecessor-version":[{"id":1287,"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/pages\/263\/revisions\/1287"}],"up":[{"embeddable":true,"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/pages\/108"}],"wp:attachment":[{"href":"https:\/\/www.afiformations.com\/fr\/wp-json\/wp\/v2\/media?parent=263"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}